{"id":60662,"date":"2021-06-29T18:22:46","date_gmt":"2021-06-29T16:22:46","guid":{"rendered":"https:\/\/mestergull.no\/olsen-drammen\/?p=60662"},"modified":"2021-06-29T18:22:46","modified_gmt":"2021-06-29T16:22:46","slug":"dark-department","status":"publish","type":"post","link":"https:\/\/mestergull.no\/olsen-drammen\/2021\/06\/29\/dark-department\/","title":{"rendered":"DARK Department"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Norsk merkevare med base i Oslo. Produkter som gj\u00f8r deg litt lykkeligere i dag, enn du var i g\u00e5r.<\/p>\n","protected":false},"author":64,"featured_media":60692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[318],"tags":[],"class_list":["post-60662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kolleksjoner"],"acf":[],"_links":{"self":[{"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/posts\/60662"}],"collection":[{"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/comments?post=60662"}],"version-history":[{"count":3,"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/posts\/60662\/revisions"}],"predecessor-version":[{"id":60695,"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/posts\/60662\/revisions\/60695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/media\/60692"}],"wp:attachment":[{"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/media?parent=60662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/categories?post=60662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mestergull.no\/olsen-drammen\/wp-json\/wp\/v2\/tags?post=60662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}